{"id":17819,"date":"2024-10-02T13:31:00","date_gmt":"2024-10-02T20:31:00","guid":{"rendered":"https:\/\/ameripharmaspe.wpengine.com\/?p=17819"},"modified":"2026-03-25T09:09:06","modified_gmt":"2026-03-25T16:09:06","slug":"medicare-ivig-coverage","status":"publish","type":"post","link":"https:\/\/ameripharmaspecialty.com\/es\/ivig\/medicare-ivig-coverage\/","title":{"rendered":"Gu\u00eda esencial para la cobertura de IgIV Medicare"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">El Medicare cubre las terapias con IgIV y IgSC en muchos casos, pero comprender los detalles a veces puede ser dif\u00edcil. Esta gu\u00eda ofrece una descripci\u00f3n general de c\u00f3mo se cubren las terapias con Ig en el Medicare. <\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Medicare brindar\u00e1 cobertura para <a href=\"https:\/\/ameripharmaspecialty.com\/es\/ivig\/ivig\/\/ivig\/\">IgIV<\/a> Residencia en:<\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">El diagn\u00f3stico<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">La ubicaci\u00f3n de la terapia<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">La v\u00eda de administraci\u00f3n&nbsp;<\/span><\/li>\n<\/ul>\n\n\n\n<p><span style=\"font-weight: 400;\">Los c\u00f3digos de diagn\u00f3stico y otros criterios se utilizan para determinar si la IgIV est\u00e1 cubierta por la Parte B de Medicare. Si tiene una afecci\u00f3n que no est\u00e1 cubierta por la Parte B, es posible que a\u00fan est\u00e9 cubierto por Medicare Part D si su afecci\u00f3n figura como una indicaci\u00f3n de IgIV aprobada por la FDA.<\/span><\/p>\n\n\n\n<div  id=\"call-to-action-0c3e680cde12c8403bb955adcbf0094d\" style=\"\" class=\"ct_call_to_action\">\n\t<div class=\"container\">\n\t\t<div class=\"block-wrap cta\">\n\t\t\t<div class=\"block-column\">\n\t\t\t\t<div class=\"cta_headings\">\n\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"cta__heading\">\n\t\t\t\t\t\t\tHable con un especialista en IgIV\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<span class=\"cta_btn\">\n\t\t\t\t\t\t<a href=\"tel:8777780318\">(877) 778-0318<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenido\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Palanca<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/ameripharmaspecialty.com\/es\/ivig\/medicare-ivig-coverage\/#Medicare_IVIG_Coverage_Under_Part_B\" >Medicare Cobertura de IgIV seg\u00fan la Parte B<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/ameripharmaspecialty.com\/es\/ivig\/medicare-ivig-coverage\/#Medicare-covered_Diagnosis_Codes_for_Part_B\" >C\u00f3digos de diagn\u00f3stico cubiertos por Medicare para la Parte B:<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/ameripharmaspecialty.com\/es\/ivig\/medicare-ivig-coverage\/#Medicare_IVIG_Coverage_Under_Part_D\" >Medicare Cobertura de IgIV seg\u00fan la Parte D<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/ameripharmaspecialty.com\/es\/ivig\/medicare-ivig-coverage\/#Medicare-Covered_FDA-approved_Indications_for_IVIG\" >Medicare-Indicaciones aprobadas por la FDA para IgIV<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/ameripharmaspecialty.com\/es\/ivig\/medicare-ivig-coverage\/#Nursing_Costs_for_IVIG\" >Costos de enfermer\u00eda para IgIV<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/ameripharmaspecialty.com\/es\/ivig\/medicare-ivig-coverage\/#Copay_Assistance\" >Asistencia para copagos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/ameripharmaspecialty.com\/es\/ivig\/medicare-ivig-coverage\/#How_to_Enroll_in_Medicare\" >C\u00f3mo inscribirse en Medicare<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/ameripharmaspecialty.com\/es\/ivig\/medicare-ivig-coverage\/#The_Inflation_Reduction_Act\" >La Ley de Reducci\u00f3n de la Inflaci\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/ameripharmaspecialty.com\/es\/ivig\/medicare-ivig-coverage\/#FAQs\" >Preguntas frecuentes<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\" id=\"h-medicare-ivig-coverage-under-part-b\"><span class=\"ez-toc-section\" id=\"Medicare_IVIG_Coverage_Under_Part_B\"><\/span><span style=\"font-weight: 400;\">Medicare Cobertura de IgIV seg\u00fan la Parte B<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">La IgIV est\u00e1 cubierta por la Parte B de Medicare si se cumplen los siguientes criterios:<\/span><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">La IgIV se administra en casa.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">La IgIV se administra a trav\u00e9s de una bomba de infusi\u00f3n.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">El m\u00e9dico tratante ha determinado que la administraci\u00f3n de IgIV en el hogar es m\u00e9dicamente apropiada.<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Al paciente se le diagnostica enfermedad de inmunodeficiencia primaria con uno de los c\u00f3digos de diagn\u00f3stico que se enumeran a continuaci\u00f3n.<\/span><\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-medicare-covered-diagnosis-codes-for-part-b\"><span class=\"ez-toc-section\" id=\"Medicare-covered_Diagnosis_Codes_for_Part_B\"><\/span><span style=\"font-weight: 400;\">C\u00f3digos de diagn\u00f3stico cubiertos por Medicare para la Parte B:<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><b>C\u00f3digo<\/b><\/td><td><b>Descripci\u00f3n<\/b><\/td><\/tr><tr><td><span style=\"font-weight: 400;\">D80.0<\/span><\/td><td>Hipogammaglobulinemia hereditaria<\/td><\/tr><tr><td><span style=\"font-weight: 400;\">D80.2<\/span><\/td><td><span style=\"font-weight: 400;\">Deficiencia selectiva de inmunoglobulina A (IgA)<\/span><\/td><\/tr><tr><td><span style=\"font-weight: 400;\">D80.3<\/span><\/td><td><span style=\"font-weight: 400;\">Deficiencia selectiva de subclases de inmunoglobulina G (IgG)<\/span><\/td><\/tr><tr><td><span style=\"font-weight: 400;\">D80.4<\/span><\/td><td><span style=\"font-weight: 400;\">Deficiencia selectiva de subclases de inmunoglobulina M (IgM)<\/span><\/td><\/tr><tr><td><span style=\"font-weight: 400;\">D80.5<\/span><\/td><td><span style=\"font-weight: 400;\">Inmunodeficiencia con aumento de inmunoglobulina M (IgM)<\/span><\/td><\/tr><tr><td><span style=\"font-weight: 400;\">D80.6<\/span><\/td><td><span style=\"font-weight: 400;\">Deficiencia de anticuerpos con inmunoglobulinas casi normales o con hiperinmunoglobulinemia.<\/span><\/td><\/tr><tr><td><span style=\"font-weight: 400;\">D80.7<\/span><\/td><td><span style=\"font-weight: 400;\">C\u00f3digo de diagn\u00f3stico CIE-10 para la hipogammaglobulinemia transitoria de la infancia.<\/span><\/td><\/tr><tr><td><span style=\"font-weight: 400;\">D81.0<\/span><\/td><td><span style=\"font-weight: 400;\">Inmunodeficiencia combinada grave (IDCG) con disgenesia reticular<\/span><\/td><\/tr><tr><td><span style=\"font-weight: 400;\">D81.1<\/span><\/td><td><span style=\"font-weight: 400;\">Inmunodeficiencia combinada grave (SCID) con bajo n\u00famero de c\u00e9lulas T y B<\/span><\/td><\/tr><tr><td><span style=\"font-weight: 400;\">D81.2<\/span><\/td><td><span style=\"font-weight: 400;\">Inmunodeficiencia combinada grave (SCID) con n\u00famero bajo o normal de c\u00e9lulas B<\/span><\/td><\/tr><tr><td><span style=\"font-weight: 400;\">D81.5<\/span><\/td><td><span style=\"font-weight: 400;\">Deficiencia de purina nucle\u00f3sido fosforilasa (PNP)<\/span><\/td><\/tr><tr><td><span style=\"font-weight: 400;\">D81.6<\/span><\/td><td><span style=\"font-weight: 400;\">Deficiencia del complejo mayor de histocompatibilidad de clase I<\/span><\/td><\/tr><tr><td><span style=\"font-weight: 400;\">D81.7<\/span><\/td><td><span style=\"font-weight: 400;\">Deficiencia del complejo mayor de histocompatibilidad clase II<\/span><\/td><\/tr><tr><td><span style=\"font-weight: 400;\">D81.9<\/span><\/td><td><span style=\"font-weight: 400;\">Inmunodeficiencia combinada, no especificada.<\/span><\/td><\/tr><tr><td><span style=\"font-weight: 400;\">D81.89<\/span><\/td><td><span style=\"font-weight: 400;\">Otras inmunodeficiencias combinadas<\/span><\/td><\/tr><tr><td><span style=\"font-weight: 400;\">D82.0<\/span><\/td><td><span style=\"font-weight: 400;\">S\u00edndrome de Wiskott-Aldrich<\/span><\/td><\/tr><tr><td><span style=\"font-weight: 400;\">D82.1<\/span><\/td><td><span style=\"font-weight: 400;\">S\u00edndrome de DiGeorge.<\/span><\/td><\/tr><tr><td><span style=\"font-weight: 400;\">D82.4<\/span><\/td><td><span style=\"font-weight: 400;\"> C\u00f3digo de diagn\u00f3stico CIE-10 para el s\u00edndrome de hiperinmunoglobulina E (IgE).<\/span><\/td><\/tr><tr><td><span style=\"font-weight: 400;\">D83.0<\/span><\/td><td><span style=\"font-weight: 400;\">Inmunodeficiencia variable com\u00fan con anomal\u00edas predominantes en el n\u00famero y la funci\u00f3n de las c\u00e9lulas B<\/span><\/td><\/tr><tr><td><span style=\"font-weight: 400;\">D83.1<\/span><\/td><td><span style=\"font-weight: 400;\">Un c\u00f3digo ICD-10-CM facturable\/espec\u00edfico que se puede utilizar para indicar un diagn\u00f3stico a efectos de reembolso<\/span><\/td><\/tr><tr><td><span style=\"font-weight: 400;\">D83.2<\/span><\/td><td><span style=\"font-weight: 400;\">Inmunodeficiencia variable com\u00fan con autoanticuerpos contra c\u00e9lulas B o T<\/span><\/td><\/tr><tr><td><span style=\"font-weight: 400;\">D83.8<\/span><\/td><td><span style=\"font-weight: 400;\">Otras inmunodeficiencias variables comunes<\/span><\/td><\/tr><tr><td><span style=\"font-weight: 400;\">D83.9<\/span><\/td><td><span style=\"font-weight: 400;\">Inmunodeficiencia com\u00fan variable, no especificada<\/span><\/td><\/tr><tr><td><span style=\"font-weight: 400;\">G11.3<\/span><\/td><td><span style=\"font-weight: 400;\">Ataxia cerebelosa con reparaci\u00f3n defectuosa del ADN<\/span><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"h-nbsp\">&nbsp;<\/h5>\n\n\n\n<div  id=\"call-to-action-9a3d9f0d903a9eec8df353f54458bd30\" style=\"\" class=\"ct_call_to_action\">\n\t<div class=\"container\">\n\t\t<div class=\"block-wrap cta\">\n\t\t\t<div class=\"block-column\">\n\t\t\t\t<div class=\"cta_headings\">\n\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"cta__heading\">\n\t\t\t\t\t\t\t\u00bfPuede ayudar la IgIV?\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"cta__sub__heading\">\n\t\t\t\t\t\t\tInformaci\u00f3n gratuita sobre el tratamiento con IgIV | \u00bfDificultad para diagnosticar?\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<span class=\"cta_btn\">\n\t\t\t\t\t\t<a href=\"#form\">Programar una consulta<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<p><span style=\"font-weight: 400;\">Medicare pagar\u00e1 80% del costo del medicamento. Los 20% restantes deben estar cubiertos por un plan complementario o por el paciente. La Parte B solo cubre el costo del medicamento. Los suministros y las bombas de infusi\u00f3n no est\u00e1n cubiertos, a menos que sean para la CIDP.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Para <a href=\"https:\/\/ameripharmaspecialty.com\/es\/cidp\/what-is-cidp\/\">PDIC<\/a>Medicare tambi\u00e9n cubrir\u00e1 80% del costo de suministros y bombas de infusi\u00f3n. A partir de julio de 2021, solo se ofrece terapia subcut\u00e1nea con IG (como Hizentra y Hyqvia).<\/span><span style=\"font-weight: 400;\"> para PDIC est\u00e1 cubierto por la Parte B.<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-medicare-ivig-coverage-under-part-d\"><span class=\"ez-toc-section\" id=\"Medicare_IVIG_Coverage_Under_Part_D\"><\/span><span style=\"font-weight: 400;\">Medicare Cobertura de IgIV seg\u00fan la Parte D<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">Para los diagn\u00f3sticos que no est\u00e1n cubiertos por la Parte B, puede aplicarse la cobertura de la Parte D si la afecci\u00f3n es una indicaci\u00f3n de IgIV aprobada por la FDA (ver a continuaci\u00f3n). <\/span>El Medicare tambi\u00e9n puede cubrir el uso no autorizado de IgIV cuando se considere m\u00e9dicamente necesario y est\u00e9 respaldado por evidencia suficiente. Por ejemplo, con base en una solicitud de reconsideraci\u00f3n recibida en diciembre de 2024, se ha evaluado rigurosamente el uso no autorizado de IgIV para el s\u00edndrome de Susac. <a href=\"https:\/\/www.cms.gov\/medicare-coverage-database\/view\/lcd.aspx?lcdid=39314&amp;ver=11\">Se ha ampliado la cobertura fuera de etiqueta<\/a>Fecha de vigencia de la revisi\u00f3n: para servicios prestados a partir del 7\/9\/2025.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-medicare-covered-fda-approved-indications-for-ivig\"><span class=\"ez-toc-section\" id=\"Medicare-Covered_FDA-approved_Indications_for_IVIG\"><\/span><span style=\"font-weight: 400;\">Medicare-Indicaciones aprobadas por la FDA para IgIV<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><span style=\"font-weight: 400;\">Inmunodeficiencia primaria<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Miastenia gravis<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Polineuropat\u00eda desmielinizante inflamatoria cr\u00f3nica (PDIC)<\/span><\/li>\n\n\n\n<li><a href=\"https:\/\/ameripharmaspecialty.com\/es\/other-health-conditions\/idiopathic-thrombocytopenic-purpura-itp\/\"><span style=\"font-weight: 400;\">P\u00farpura trombocitop\u00e9nica inmunitaria (PTI)<\/span><\/a><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Leucemia linfoc\u00edtica cr\u00f3nica de c\u00e9lulas B (LLC)<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">S\u00edndrome de la persona r\u00edgida<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Trasplante de m\u00e9dula \u00f3sea\/trasplante de c\u00e9lulas madre hematopoy\u00e9ticas<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Dermatomiositis<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Polimiositis<\/span><\/li>\n\n\n\n<li><a href=\"https:\/\/ameripharmaspecialty.com\/es\/other-health-conditions\/what-is-multifocal-motor-neuropathy-mmn\/\"><span style=\"font-weight: 400;\">Neuropat\u00eda motora multifocal<\/span><\/a><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">infecci\u00f3n por VIH<\/span><\/li>\n\n\n\n<li><a href=\"https:\/\/ameripharmaspecialty.com\/es\/guillain-barre-syndrome\/gbs-guillain-barre-syndrome\/\"><span style=\"font-weight: 400;\">S\u00edndrome de Guillain-Barr\u00e9<\/span><\/a><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">S\u00edndrome miast\u00e9nico de Lambert-Eaton<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Aplasia pura de gl\u00f3bulos rojos inducida por parvovirus B19<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">S\u00edndrome de Kawasaki (pedi\u00e1trico)<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Trombocitopenia aloinmune fetal\/neonatal<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Enfermedad hemol\u00edtica isoinmune del reci\u00e9n nacido<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Hemocromatosis neonatal<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Toxicidad relacionada con los inhibidores de puntos de control inmunitario<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Hipogammaglobulinemia relacionada con la terapia CAR-T<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Aplasia adquirida de gl\u00f3bulos rojos<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Encefalomielitis aguda diseminada<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Encefalitis de Rasmussen<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Meningoencefalitis enteroviral<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Enfermedad ampollosa mucocut\u00e1nea autoinmune<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">anemia hemol\u00edtica autoinmune<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Neutropenia autoinmune<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Lupus eritematoso sist\u00e9mico<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Retinocoroidopat\u00eda en perdigones<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Nefropat\u00eda asociada al virus BK<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">S\u00edndrome de Churg-Strauss<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Linfohistiocitosis hematofagoc\u00edtica (HLH)<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">S\u00edndrome de activaci\u00f3n de macr\u00f3fagos (SAM)<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">S\u00edndrome de hiperinmunoglobulinemia E<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Mieloma m\u00faltiple<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">opsoclono-mioclono<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">P\u00farpura postransfusional<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Trasplante de \u00f3rganos s\u00f3lidos<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Inmunosupresi\u00f3n secundaria asociada a cirug\u00eda mayor<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Inmunosupresi\u00f3n secundaria asociada a malignidad hematol\u00f3gica<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Inmunosupresi\u00f3n secundaria asociada a quemaduras mayores<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Inmunosupresi\u00f3n secundaria asociada a la enfermedad vascular del col\u00e1geno<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Necr\u00f3lisis epid\u00e9rmica t\u00f3xica<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">S\u00edndrome de Stevens-Johnson<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">S\u00edndrome de shock t\u00f3xico<\/span><\/li>\n\n\n\n<li><span style=\"font-weight: 400;\">Fascitis necrosante t\u00f3xica<\/span><\/li>\n<\/ul>\n\n\n\n<p><span style=\"font-weight: 400;\">Se aplican las estructuras de beneficios y copagos de la Parte D est\u00e1ndar.&nbsp;<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Para obtener m\u00e1s informaci\u00f3n sobre los gastos de bolsillo de la Parte D, <\/span><a href=\"https:\/\/q1medicare.com\/\"><span style=\"font-weight: 400;\">Visita el sitio Q1Medicare<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-nursing-costs-for-ivig\"><span class=\"ez-toc-section\" id=\"Nursing_Costs_for_IVIG\"><\/span><span style=\"font-weight: 400;\">Costos de enfermer\u00eda para IgIV<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright\"><img loading=\"lazy\" decoding=\"async\" width=\"420\" height=\"280\" src=\"https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/ivig-nurse.jpg\" alt=\"IVIG nurse\" class=\"wp-image-17856\" srcset=\"https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/ivig-nurse.jpg 420w, https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/ivig-nurse-300x200.jpg 300w, https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/ivig-nurse-330x220.jpg 330w, https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/ivig-nurse-86x57.jpg 86w, https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/ivig-nurse-167x111.jpg 167w, https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/ivig-nurse-280x187.jpg 280w, https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/ivig-nurse-370x247.jpg 370w\" sizes=\"auto, (max-width: 420px) 100vw, 420px\" \/><\/figure>\n<\/div>\n\n\n<p><span style=\"font-weight: 400;\">Enfermer\u00eda <a href=\"https:\/\/ameripharmaspecialty.com\/es\/ivig\/cost-of-ivig-treatment\/\">costos de IgIV<\/a> est\u00e1n cubiertos por la <a href=\"https:\/\/www.aarp.org\/health\/medicare-qa-tool\/what-is-original-medicare\/\">Original Medicare<\/a> o <a href=\"https:\/\/www.medicare.gov\/health-drug-plans\/health-plans\/your-health-plan-options\">Ventaja del Medicare<\/a> Plan. Para el plan original Medicare, el 80% de los costos estar\u00e1n cubiertos por el plan, y un plan complementario o el paciente ser\u00e1n responsables de los 20% restantes.&nbsp;<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Los costos var\u00edan seg\u00fan el plan Advantage Medicare. Se requiere una investigaci\u00f3n completa de beneficios para determinar el costo exacto. Para m\u00e1s informaci\u00f3n, consulte con un especialista en facturaci\u00f3n de AmeriPharma\u00ae.<\/span><\/p>\n\n\n\n<div  id=\"call-to-action-317eea4bc192af08ca55ac4a04001a67\" style=\"\" class=\"ct_call_to_action\">\n\t<div class=\"container\">\n\t\t<div class=\"block-wrap cta\">\n\t\t\t<div class=\"block-column\">\n\t\t\t\t<div class=\"cta_headings\">\n\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"cta__heading\">\n\t\t\t\t\t\t\tConsulte con un especialista en facturaci\u00f3n de AmeriPharma\u00ae\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<span class=\"cta_btn\">\n\t\t\t\t\t\t<a href=\"tel:8777780318\">(877) 778-0318<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-copay-assistance\"><span class=\"ez-toc-section\" id=\"Copay_Assistance\"><\/span><span style=\"font-weight: 400;\">Asistencia para copagos<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">AmeriPharma\u00ae ofrece asistencia para cubrir cualquier copago restante que pueda tener en IgIV despu\u00e9s de usar Medicare. Mediante un software avanzado, AmeriPharma\u00ae revisar\u00e1 todas las fuentes de financiaci\u00f3n disponibles y le asignar\u00e1 un programa que se ajuste a sus necesidades. Un especialista en copagos le ayudar\u00e1 con el proceso de solicitud.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">Para obtener m\u00e1s informaci\u00f3n, hable con uno de nuestros especialistas sobre c\u00f3mo AmeriPharma\u00ae puede ayudarle.<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-how-to-enroll-in-medicare\"><span class=\"ez-toc-section\" id=\"How_to_Enroll_in_Medicare\"><\/span><span style=\"font-weight: 400;\">C\u00f3mo inscribirse en Medicare<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><span style=\"font-weight: 400;\">Puede inscribirse para el formulario Medicare en l\u00ednea, por tel\u00e9fono o en persona en su oficina local del Seguro Social.<\/span><\/p>\n\n\n\n<p><span style=\"font-weight: 400;\">La inscripci\u00f3n en Medicare est\u00e1 disponible durante un per\u00edodo de inscripci\u00f3n de 7 meses que comienza 3 meses antes de cumplir 65 a\u00f1os. Debe inscribirse en Medicare antes de cumplir 65 a\u00f1os si desea que su cobertura comience el mes en que cumpla 65 a\u00f1os. Tambi\u00e9n puede inscribirse en Medicare hasta 3 meses despu\u00e9s del mes en que cumpla 65 a\u00f1os, como se describe en el sitio web de Medicare.&nbsp;<\/span><\/p>\n\n\n\n<p>Las personas con discapacidades espec\u00edficas pueden <a href=\"https:\/\/medicareadvocacy.org\/medicare-info\/medicare-coverage-for-people-with-disabilities\/\">calificar para Medicare antes de cumplir 65 a\u00f1os<\/a>.<\/p>\n\n\n\n<p>El per\u00edodo de inscripci\u00f3n abierta Medicare 2025 es del 15 de octubre al 7 de diciembre de 2025. Los cambios realizados durante este tiempo entrar\u00e1n en vigor el 1 de enero de 2026.<\/p>\n\n\n\n<p>Durante este tiempo, los afiliados a Medicare pueden revisar y realizar cambios en su cobertura actual, incluidos los costos, la cobertura y las redes de proveedores y farmacias.<\/p>\n\n\n\n<p>El per\u00edodo de inscripci\u00f3n abierta de Medicare tambi\u00e9n se conoce como &quot;per\u00edodo de inscripci\u00f3n anual&quot; o &quot;PEA&quot;. Tambi\u00e9n puede haber otros per\u00edodos durante el a\u00f1o en que las personas puedan inscribirse en un plan, denominados per\u00edodos de &quot;inscripci\u00f3n abierta&quot; o &quot;inscripci\u00f3n especial&quot;.&nbsp;<\/p>\n\n\n\n<p>Para obtener m\u00e1s informaci\u00f3n, <a href=\"https:\/\/www.medicare.gov\/basics\/get-started-with-medicare\/sign-up\/when-does-medicare-coverage-start\">Visita medicare.gov<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-the-inflation-reduction-act\"><span class=\"ez-toc-section\" id=\"The_Inflation_Reduction_Act\"><\/span><span style=\"font-weight: 400;\">La Ley de Reducci\u00f3n de la Inflaci\u00f3n<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Gracias a la Ley de Reducci\u00f3n de la Inflaci\u00f3n (IRA) de la Administraci\u00f3n Biden-Harris, tambi\u00e9n conocida como la ley de medicamentos recetados, las personas con cobertura de medicamentos recetados Medicare (Parte D) en 2025 tendr\u00e1n los beneficios m\u00e1s completos desde que se lanz\u00f3 el programa en 2006. A partir de 2025, todas las personas inscritas en la Parte D tienen sus costos anuales de medicamentos recetados de desembolso personal <a href=\"https:\/\/www.cms.gov\/newsroom\/news-alert\/cms-releases-preliminary-2025-medicare-part-d-bid-information-and-announces-premium-stabilization#:~:text=In%202025%2C%20all%20people%20enrolled,capped%20at%20%242%2C000%20per%20year\">con un l\u00edmite de $2,000 por a\u00f1o<\/a>Para 2026, el umbral de OOP es <a href=\"https:\/\/www.cms.gov\/newsroom\/fact-sheets\/final-cy-2026-part-d-redesign-program-instructions\">configurado para aumentar a $2100<\/a>, lo que refleja ajustes por crecimiento\/inflaci\u00f3n. En 2026, el deducible de la Parte D Medicare aumentar\u00e1 de $590 en 2025 a $615 en 2026.<\/p>\n\n\n\n<p>Adem\u00e1s, el Plan de Pago de Recetas Medicare, que ofrecen todos los planes de la Parte D, permite a las personas con cobertura Medicare Part D la opci\u00f3n de distribuir los costos de sus medicamentos recetados a lo largo del a\u00f1o calendario.<\/p>\n\n\n\n<div  id=\"call-to-action-dbb53316c15e95b51b1ca3cce82adef7\" style=\"\" class=\"ct_call_to_action\">\n\t<div class=\"container\">\n\t\t<div class=\"block-wrap cta\">\n\t\t\t<div class=\"block-column\">\n\t\t\t\t<div class=\"cta_headings\">\n\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"cta__heading\">\n\t\t\t\t\t\t\tObtenga asistencia para el copago de IgIV\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"cta__sub__heading\">\n\t\t\t\t\t\t\tAsistencia financiera para la IgIV\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<span class=\"cta_btn\">\n\t\t\t\t\t\t<a href=\"#form\">Consulte a un especialista en IgIV<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-faqs\"><span class=\"ez-toc-section\" id=\"FAQs\"><\/span><span style=\"font-weight: 400;\">Preguntas frecuentes<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-does-medicare-cover-ivig-for-cidp\"><strong>\u00bfMedicare cubre la IgIV para la CIDP?<\/strong><\/h4>\n\n\n\n<p><span style=\"font-weight: 400;\">S\u00ed. Para CIDP, Medicare cubrir\u00e1 80% del costo del medicamento y los suministros. Los 20% restantes deben estar cubiertos por un plan complementario o por el paciente. A partir de julio de 2021, solo se permite la terapia con inmunoglobulinas subcut\u00e1neas (como Hizentra y Hyqvia).<\/span>)<span style=\"font-weight: 400;\"> para PDIC est\u00e1 cubierto por la Parte B.&nbsp;<\/span><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-does-medicare-cover-ivig-for-guillain-barre-syndrome\"><strong>\u00bfMedicare cubre la IgIV para el s\u00edndrome de Guillain-Barr\u00e9?<\/strong><\/h4>\n\n\n\n<p><span style=\"font-weight: 400;\">S\u00ed. Medicare brinda cobertura para el s\u00edndrome de Guillain-Barr\u00e9 bajo la Parte D.<\/span><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-does-medicare-cover-ivig-for-myasthenia-gravis\"><strong>\u00bfMedicare cubre la IgIV para la miastenia gravis?<\/strong><\/h4>\n\n\n\n<p><span style=\"font-weight: 400;\">S\u00ed. Medicare brinda cobertura para miastenia grave seg\u00fan la Parte D.<\/span><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-is-privigen-covered-by-medicare\"><strong>\u00bfEl Privigen est\u00e1 cubierto por el Medicare?<\/strong><\/h4>\n\n\n\n<p><span style=\"font-weight: 400;\">S\u00ed, <a href=\"https:\/\/ameripharmaspecialty.com\/es\/ivig\/privigen-medication\/\">Privigen<\/a> (J1459) est\u00e1 cubierto por Medicare Parte B.&nbsp;<\/span><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-is-gamunex-covered-by-medicare\"><strong>\u00bfGamunex est\u00e1 cubierto por Medicare?<\/strong><\/h4>\n\n\n\n<p><span style=\"font-weight: 400;\">S\u00ed, <a href=\"https:\/\/ameripharmaspecialty.com\/es\/ivig\/ivig\/\/gamunex-c-the-immune-supplement\/\">Gamunex<\/a> (J1561) est\u00e1 cubierto por Medicare Parte B.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>El Medicare cubre las terapias con IgIV y IgSC en muchos casos, pero comprender los detalles a veces puede ser dif\u00edcil. Esta gu\u00eda ofrece una descripci\u00f3n general de c\u00f3mo se cubren las terapias con Ig en el Medicare.<\/p>","protected":false},"author":32,"featured_media":17855,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[7,62],"tags":[16],"class_list":["post-17819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ivig","category-medicare","tag-april-velasco-cable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Does Medicare Cover IVIG Infusions? | AmeriPharma<\/title>\n<meta name=\"description\" content=\"Does Medicare cover IVIG infusions? Explore Medicare coverage details for home and outpatient treatments, eligibility requirements, and out-of-pocket costs.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ameripharmaspecialty.com\/es\/ivig\/medicare-ivig-coverage\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Does Medicare Cover IVIG Infusions? | AmeriPharma\" \/>\n<meta property=\"og:description\" content=\"Does Medicare cover IVIG infusions? Explore Medicare coverage details for home and outpatient treatments, eligibility requirements, and out-of-pocket costs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ameripharmaspecialty.com\/es\/ivig\/medicare-ivig-coverage\/\" \/>\n<meta property=\"og:site_name\" content=\"AmeriPharma\u00ae Specialty Care\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ameripharma\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-02T20:31:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-25T16:09:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Mogote\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Mogote\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/ivig\\\/medicare-ivig-coverage\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/ivig\\\/medicare-ivig-coverage\\\/\"},\"author\":{\"name\":\"David Mogote\",\"@id\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/#\\\/schema\\\/person\\\/b8eff1de87e1d56a7426a71f8faced2d\"},\"headline\":\"The Essential Guide to Medicare IVIG Coverage\",\"datePublished\":\"2024-10-02T20:31:00+00:00\",\"dateModified\":\"2026-03-25T16:09:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/ivig\\\/medicare-ivig-coverage\\\/\"},\"wordCount\":1247,\"publisher\":{\"@id\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/ivig\\\/medicare-ivig-coverage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/medicare-ivig.jpg\",\"keywords\":[\"April Velasco Cable\"],\"articleSection\":[\"IVIG\",\"Medicare\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/ivig\\\/medicare-ivig-coverage\\\/\",\"url\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/ivig\\\/medicare-ivig-coverage\\\/\",\"name\":\"Does Medicare Cover IVIG Infusions? | AmeriPharma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/ivig\\\/medicare-ivig-coverage\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/ivig\\\/medicare-ivig-coverage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/medicare-ivig.jpg\",\"datePublished\":\"2024-10-02T20:31:00+00:00\",\"dateModified\":\"2026-03-25T16:09:06+00:00\",\"description\":\"Does Medicare cover IVIG infusions? Explore Medicare coverage details for home and outpatient treatments, eligibility requirements, and out-of-pocket costs.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/ivig\\\/medicare-ivig-coverage\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ameripharmaspecialty.com\\\/ivig\\\/medicare-ivig-coverage\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/ivig\\\/medicare-ivig-coverage\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/medicare-ivig.jpg\",\"contentUrl\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/medicare-ivig.jpg\",\"width\":1280,\"height\":853,\"caption\":\"Medicare coverage for IVIG\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/ivig\\\/medicare-ivig-coverage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Essential Guide to Medicare IVIG Coverage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/#website\",\"url\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/\",\"name\":\"AmeriPharma\u00ae Specialty Care\",\"description\":\"Specialty Care by AmeriPharma\",\"publisher\":{\"@id\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/#organization\",\"name\":\"Ameripharma Specialty Care\",\"url\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/specialty-care-logo-large-square.png\",\"contentUrl\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/specialty-care-logo-large-square.png\",\"width\":400,\"height\":400,\"caption\":\"Ameripharma Specialty Care\"},\"image\":{\"@id\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ameripharma\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/#\\\/schema\\\/person\\\/b8eff1de87e1d56a7426a71f8faced2d\",\"name\":\"David Mogote\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/abb204e872efb97d75d347768bc3e2625c56f3978eaae2ca7dc464f55cae5af1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/abb204e872efb97d75d347768bc3e2625c56f3978eaae2ca7dc464f55cae5af1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/abb204e872efb97d75d347768bc3e2625c56f3978eaae2ca7dc464f55cae5af1?s=96&d=mm&r=g\",\"caption\":\"David Mogote\"},\"description\":\"David Mogote is currently the Director of Revenue Cycle Management at AmeriPharma. He was born and raised in Norwalk, CA, and received his degree from Cypress College in 2002. The most rewarding part of his job is helping patients understand their healthcare benefits and seeking the best outcome to assist them with their high out-of-pocket expenses. Mogote has seen the home infusion industry grow from the inside out, and has witnessed the many changes in commercial, government, and private healthcare systems, allowing him to amass a wealth of experience and understanding. In his free time, he enjoys spending time with his family on weekend outings and trips to the beach.\",\"url\":\"https:\\\/\\\/ameripharmaspecialty.com\\\/es\\\/author\\\/david-mogote\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfCubre el Medicare las infusiones de IVIG? | AmeriPharma","description":"\u00bfCubre el plan Medicare las infusiones de inmunoglobulina intravenosa (IVIG)? Consulte los detalles de la cobertura del plan Medicare para tratamientos ambulatorios y en el hogar, los requisitos de elegibilidad y los costos que deber\u00e1 pagar de su bolsillo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ameripharmaspecialty.com\/es\/ivig\/medicare-ivig-coverage\/","og_locale":"es_MX","og_type":"article","og_title":"Does Medicare Cover IVIG Infusions? | AmeriPharma","og_description":"Does Medicare cover IVIG infusions? Explore Medicare coverage details for home and outpatient treatments, eligibility requirements, and out-of-pocket costs.","og_url":"https:\/\/ameripharmaspecialty.com\/es\/ivig\/medicare-ivig-coverage\/","og_site_name":"AmeriPharma\u00ae Specialty Care","article_publisher":"https:\/\/www.facebook.com\/ameripharma\/","article_published_time":"2024-10-02T20:31:00+00:00","article_modified_time":"2026-03-25T16:09:06+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig.jpg","type":"image\/jpeg"}],"author":"David Mogote","twitter_card":"summary_large_image","twitter_misc":{"Written by":"David Mogote","Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ameripharmaspecialty.com\/ivig\/medicare-ivig-coverage\/#article","isPartOf":{"@id":"https:\/\/ameripharmaspecialty.com\/ivig\/medicare-ivig-coverage\/"},"author":{"name":"David Mogote","@id":"https:\/\/ameripharmaspecialty.com\/#\/schema\/person\/b8eff1de87e1d56a7426a71f8faced2d"},"headline":"The Essential Guide to Medicare IVIG Coverage","datePublished":"2024-10-02T20:31:00+00:00","dateModified":"2026-03-25T16:09:06+00:00","mainEntityOfPage":{"@id":"https:\/\/ameripharmaspecialty.com\/ivig\/medicare-ivig-coverage\/"},"wordCount":1247,"publisher":{"@id":"https:\/\/ameripharmaspecialty.com\/#organization"},"image":{"@id":"https:\/\/ameripharmaspecialty.com\/ivig\/medicare-ivig-coverage\/#primaryimage"},"thumbnailUrl":"https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig.jpg","keywords":["April Velasco Cable"],"articleSection":["IVIG","Medicare"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/ameripharmaspecialty.com\/ivig\/medicare-ivig-coverage\/","url":"https:\/\/ameripharmaspecialty.com\/ivig\/medicare-ivig-coverage\/","name":"\u00bfCubre el Medicare las infusiones de IVIG? | AmeriPharma","isPartOf":{"@id":"https:\/\/ameripharmaspecialty.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ameripharmaspecialty.com\/ivig\/medicare-ivig-coverage\/#primaryimage"},"image":{"@id":"https:\/\/ameripharmaspecialty.com\/ivig\/medicare-ivig-coverage\/#primaryimage"},"thumbnailUrl":"https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig.jpg","datePublished":"2024-10-02T20:31:00+00:00","dateModified":"2026-03-25T16:09:06+00:00","description":"\u00bfCubre el plan Medicare las infusiones de inmunoglobulina intravenosa (IVIG)? Consulte los detalles de la cobertura del plan Medicare para tratamientos ambulatorios y en el hogar, los requisitos de elegibilidad y los costos que deber\u00e1 pagar de su bolsillo.","breadcrumb":{"@id":"https:\/\/ameripharmaspecialty.com\/ivig\/medicare-ivig-coverage\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ameripharmaspecialty.com\/ivig\/medicare-ivig-coverage\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ameripharmaspecialty.com\/ivig\/medicare-ivig-coverage\/#primaryimage","url":"https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig.jpg","contentUrl":"https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig.jpg","width":1280,"height":853,"caption":"Medicare coverage for IVIG"},{"@type":"BreadcrumbList","@id":"https:\/\/ameripharmaspecialty.com\/ivig\/medicare-ivig-coverage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ameripharmaspecialty.com\/"},{"@type":"ListItem","position":2,"name":"The Essential Guide to Medicare IVIG Coverage"}]},{"@type":"WebSite","@id":"https:\/\/ameripharmaspecialty.com\/#website","url":"https:\/\/ameripharmaspecialty.com\/","name":"Cuidado especializado AmeriPharma\u00ae","description":"Atenci\u00f3n especializada por AmeriPharma","publisher":{"@id":"https:\/\/ameripharmaspecialty.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ameripharmaspecialty.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ameripharmaspecialty.com\/#organization","name":"Atenci\u00f3n especializada de Ameripharma","url":"https:\/\/ameripharmaspecialty.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ameripharmaspecialty.com\/#\/schema\/logo\/image\/","url":"https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2024\/07\/specialty-care-logo-large-square.png","contentUrl":"https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2024\/07\/specialty-care-logo-large-square.png","width":400,"height":400,"caption":"Ameripharma Specialty Care"},"image":{"@id":"https:\/\/ameripharmaspecialty.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ameripharma\/"]},{"@type":"Person","@id":"https:\/\/ameripharmaspecialty.com\/#\/schema\/person\/b8eff1de87e1d56a7426a71f8faced2d","name":"David Mogote","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/abb204e872efb97d75d347768bc3e2625c56f3978eaae2ca7dc464f55cae5af1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/abb204e872efb97d75d347768bc3e2625c56f3978eaae2ca7dc464f55cae5af1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/abb204e872efb97d75d347768bc3e2625c56f3978eaae2ca7dc464f55cae5af1?s=96&d=mm&r=g","caption":"David Mogote"},"description":"David Mogote es actualmente Director de Gesti\u00f3n del Ciclo de Ingresos en AmeriPharma. Naci\u00f3 y creci\u00f3 en Norwalk, California, y se gradu\u00f3 de Cypress College en 2002. La parte m\u00e1s gratificante de su trabajo es ayudar a los pacientes a comprender sus beneficios de atenci\u00f3n m\u00e9dica y buscar la mejor soluci\u00f3n para ayudarles con sus elevados gastos de bolsillo. Mogote ha visto crecer la industria de la infusi\u00f3n domiciliaria desde dentro y ha sido testigo de los numerosos cambios en los sistemas de salud comerciales, gubernamentales y privados, lo que le ha permitido acumular una vasta experiencia y conocimiento. En su tiempo libre, disfruta de pasar tiempo con su familia en salidas de fin de semana y viajes a la playa.","url":"https:\/\/ameripharmaspecialty.com\/es\/author\/david-mogote\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig.jpg",1280,853,false],"thumbnail":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig-150x150.jpg",150,150,true],"medium":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig-300x200.jpg",300,200,true],"medium_large":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig-768x512.jpg",768,512,true],"large":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig-1024x682.jpg",1024,682,true],"1536x1536":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig.jpg",1280,853,false],"2048x2048":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig.jpg",1280,853,false],"trp-custom-language-flag":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig.jpg",18,12,false],"block-image-html-large":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig.jpg",600,400,false],"ct-gallery":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig-330x220.jpg",330,220,true],"ct-section-header":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig-1146x380.jpg",1146,380,true],"ct-thumb":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig-86x57.jpg",86,57,true],"ct-thumb-large":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig-167x111.jpg",167,111,true],"ct-small":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig-280x187.jpg",280,187,true],"ct-medium":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig-370x247.jpg",370,247,true],"ct-xmedium":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig-960x640.jpg",960,640,true],"ct-large":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig.jpg",1280,853,false]},"uagb_author_info":{"display_name":"David Mogote","author_link":"https:\/\/ameripharmaspecialty.com\/es\/author\/david-mogote\/"},"uagb_comment_info":0,"uagb_excerpt":"Medicare provides coverage for IVIG and SCIG therapies in many instances, but navigating the details can sometimes be difficult. This guide will provide an overview of how IG therapies are covered under Medicare.","rttpg_featured_image_url":{"full":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig.jpg",1280,853,false],"landscape":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig.jpg",1280,853,false],"portraits":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig.jpg",1280,853,false],"thumbnail":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig-150x150.jpg",150,150,true],"medium":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig-300x200.jpg",300,200,true],"large":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig-1024x682.jpg",1024,682,true],"1536x1536":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig.jpg",1280,853,false],"2048x2048":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig.jpg",1280,853,false],"trp-custom-language-flag":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig.jpg",18,12,false],"block-image-html-large":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig.jpg",600,400,false],"ct-gallery":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig-330x220.jpg",330,220,true],"ct-section-header":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig-1146x380.jpg",1146,380,true],"ct-thumb":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig-86x57.jpg",86,57,true],"ct-thumb-large":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig-167x111.jpg",167,111,true],"ct-small":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig-280x187.jpg",280,187,true],"ct-medium":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig-370x247.jpg",370,247,true],"ct-xmedium":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig-960x640.jpg",960,640,true],"ct-large":["https:\/\/ameripharmaspecialty.com\/wp-content\/uploads\/2021\/12\/medicare-ivig.jpg",1280,853,false]},"rttpg_author":{"display_name":"David Mogote","author_link":"https:\/\/ameripharmaspecialty.com\/es\/author\/david-mogote\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/ameripharmaspecialty.com\/es\/category\/ivig\/\" rel=\"category tag\">IVIG<\/a> <a href=\"https:\/\/ameripharmaspecialty.com\/es\/category\/medicare\/\" rel=\"category tag\">Medicare<\/a>","rttpg_excerpt":"Medicare provides coverage for IVIG and SCIG therapies in many instances, but navigating the details can sometimes be difficult. This guide will provide an overview of how IG therapies are covered under Medicare.","_links":{"self":[{"href":"https:\/\/ameripharmaspecialty.com\/es\/wp-json\/wp\/v2\/posts\/17819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ameripharmaspecialty.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ameripharmaspecialty.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ameripharmaspecialty.com\/es\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/ameripharmaspecialty.com\/es\/wp-json\/wp\/v2\/comments?post=17819"}],"version-history":[{"count":0,"href":"https:\/\/ameripharmaspecialty.com\/es\/wp-json\/wp\/v2\/posts\/17819\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ameripharmaspecialty.com\/es\/wp-json\/wp\/v2\/media\/17855"}],"wp:attachment":[{"href":"https:\/\/ameripharmaspecialty.com\/es\/wp-json\/wp\/v2\/media?parent=17819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ameripharmaspecialty.com\/es\/wp-json\/wp\/v2\/categories?post=17819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ameripharmaspecialty.com\/es\/wp-json\/wp\/v2\/tags?post=17819"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}